{"id":2166,"date":"2015-09-21T11:05:19","date_gmt":"2015-09-21T10:05:19","guid":{"rendered":"http:\/\/blogs.lavozdegalicia.es\/victorsalgado\/?p=2166"},"modified":"2015-09-21T11:08:09","modified_gmt":"2015-09-21T10:08:09","slug":"hay-derecho-en-las-redes-sociales","status":"publish","type":"post","link":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/2015\/09\/21\/hay-derecho-en-las-redes-sociales\/","title":{"rendered":"Hay Derecho en las Redes Sociales"},"content":{"rendered":"<p>Nuestro pa\u00eds siempre se ha caracterizado por ser pionero o postrero en las distintas revoluciones que han ido surgiendo a lo largo de las Historia. Desde luego, las nuevas tecnolog\u00edas no iban a ser una excepci\u00f3n.<\/p>\n<p>Sin embargo, en este caso, Espa\u00f1a fue uno de los primeros pa\u00edses del mundo en legislar en la materia. Es sorprendente comprobar que, ni m\u00e1s ni menos, que <strong>nuestra Constituci\u00f3n de 1978 ya consigno la palabra \u201cinform\u00e1tica\u201d en un art\u00edculo fundamental<\/strong>, el 18 que regula derechos tan importantes como el honor, la intimidad personal y familiar y la propia imagen. En concreto, su apartado 4 dispone expresamente que <i>\u201cLa ley limitar\u00e1 el uso de la inform\u00e1tica para garantizar el honor y la intimidad personal y familiar de los ciudadanos y el pleno ejercicio de sus derechos\u201d<\/i>.<\/p>\n<p>En un momento en que criticamos, cada vez m\u00e1s, la labor del legislador en los \u00faltimos tiempos, es importante poner en valor la gran calidad del texto de nuestra Carta Magna que lleg\u00f3 a ser verdaderamente prof\u00e9tico. \u00bfCu\u00e1ntos ordenadores hab\u00eda en Espa\u00f1a en 1978? Casi podr\u00edamos contarlos y, sin embargo, nuestro legislador constituyente ya previ\u00f3, a\u00f1os antes incluso que organismos internacionales como la OCDE, la potencial amenaza que pod\u00edan constituir las incipientes nuevas tecnolog\u00edas para los derechos fundamentales de las personas.<\/p>\n<p>Bien es cierto que <strong>tardamos 14 a\u00f1os en cumplir el mandato constitucional<\/strong> y aprobar la ya derogada Ley Org\u00e1nica 5\/1992 de Tratamiento Automatizado de Datos de car\u00e1cter Personal (LORTAD), sustituida ahora por la LOPD de 1999 y su desarrollo reglamentario de 2007, pero hoy ya podemos hablar de un verdadero derecho fundamental a la privacidad y a la protecci\u00f3n de nuestros datos en Espa\u00f1a gracias a dos sentencias claves del Tribunal Constitucional, la 291 y 292 del 30 de noviembre de 2000, que marcaron el inicio de una verdadera revoluci\u00f3n de defensa de nuestros derechos civiles en Internet.<\/p>\n<p>Sin duda, <strong>Espa\u00f1a ha sido pionera en un sistema normativo revolucionario que ahora disfrutamos en toda Europa y que miran con envidia otros pa\u00edses<\/strong> como Estados Unidos, cuyos modelos de negocio \u201cgratuitos\u201d se sostienen gracias a una explotaci\u00f3n masiva de los datos personales de los usuarios por parte de empresas multimillonarias gracias a una legislaci\u00f3n mucho menos protectora de la privacidad de los ciudadanos.<\/p>\n<p>El \u00faltimo hito ha sido la important\u00edsima <strong>sentencia del Tribunal de Justicia de la Uni\u00f3n Europea, de 13 de mayo de 2014, donde se reconoce por vez primera tanto el llamado \u201cderecho al olvido\u201d<\/strong> en la Red como, a\u00fan m\u00e1s importante, la aplicaci\u00f3n de nuestra normativa a los gigantes norteamericanos de Internet como Google o Facebook, cuando traten los datos de europeos. Dicha sentencia tambi\u00e9n fue causada, tambi\u00e9n, gracias a una acci\u00f3n judicial impulsada desde nuestro pa\u00eds.<\/p>\n<p>El hecho de que seamos pioneros a nivel mundial en la protecci\u00f3n de nuestros derechos en la Red es algo de lo que sentirnos muy orgullosos \ud83d\ude09<\/p>\n<p>&nbsp;<\/p>\n<p><em>Publicado originalmente en: <a href=\"http:\/\/www.lavozdegalicia.es\/noticia\/internet\/2015\/05\/04\/derecho-redes-sociales\/0003_201505G4P3993.htm\" target=\"_blank\">http:\/\/www.lavozdegalicia.es\/noticia\/internet\/2015\/05\/04\/derecho-redes-sociales\/0003_201505G4P3993.htm<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hecho de que seamos pioneros a nivel mundial en la protecci\u00f3n de nuestros derechos en la Red es algo de lo que sentirnos muy orgullosos.<\/p>\n","protected":false},"author":180,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,7122],"tags":[7197,40,7022,247878,7087],"class_list":["post-2166","post","type-post","status-publish","format-standard","hentry","category-general","category-proteccion-de-datos","tag-datos-personales","tag-internet","tag-privacidad","tag-proteccion-de-datos","tag-redes-sociales"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/posts\/2166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/users\/180"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/comments?post=2166"}],"version-history":[{"count":3,"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/posts\/2166\/revisions"}],"predecessor-version":[{"id":2169,"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/posts\/2166\/revisions\/2169"}],"wp:attachment":[{"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/media?parent=2166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/categories?post=2166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lavozdegalicia.es\/victorsalgado\/wp-json\/wp\/v2\/tags?post=2166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}